{"id":2561,"date":"2021-01-15T08:41:10","date_gmt":"2021-01-15T01:41:10","guid":{"rendered":"https:\/\/vcgamers.co.id\/?p=2561"},"modified":"2021-05-24T18:56:05","modified_gmt":"2021-05-24T11:56:05","slug":"tipps-master-u-boot-world-of-warships","status":"publish","type":"post","link":"https:\/\/www.vcgamers.com\/news\/de\/tips-menguasai-submarine-world-of-warships\/","title":{"rendered":"Tipps zum Meistern der Submarine World of Warships"},"content":{"rendered":"<p>Vor nicht allzu langer Zeit brachte der Wargaming-Entwickler Submarine auf den Markt, die neueste Klassenwahl f\u00fcr das Spiel World of Warships. Submarine ist in der Lage, dem Spiel mit \u00c4nderungen an der Strategie und dem verwendeten Meta eine andere Farbe zu verleihen. Wie <a href=\"https:\/\/vcgamers.co.id\/tips-trick\">richtiger Weg<\/a> mit U-Boot World of Warships?<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-2562 aligncenter\" src=\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/01\/submarine-world-of-warships-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/01\/submarine-world-of-warships-300x169.jpg 300w, https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/01\/submarine-world-of-warships-250x141.jpg 250w, https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/01\/submarine-world-of-warships-18x10.jpg 18w, https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/01\/submarine-world-of-warships-720x405.jpg 720w, https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/01\/submarine-world-of-warships.jpg 758w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<h2><strong><b>Wendigkeit<\/b><\/strong><\/h2>\n<p>Ein wichtiger Schl\u00fcssel zum Betrieb von Submarine World of Warships ist die F\u00e4higkeit, verschiedene Man\u00f6ver durchzuf\u00fchren. Im Gegensatz zu den meisten Klassen mit WASD f\u00fcr die Hauptsteuerung beim Man\u00f6vrieren hat Submarine World of Warships eine Reihe zus\u00e4tzlicher Tasten, um an die Wasseroberfl\u00e4che zu steigen, n\u00e4mlich die F-Taste, andernfalls verwenden Sie die C-Taste zum Tauchen. Wenn Sie in der Zwischenzeit die Position des Schiffes sperren m\u00f6chten, dr\u00fccken Sie Strg + F oder Strg + C. An der Oberfl\u00e4che k\u00f6nnen die Spieler die feindlichen Positionen leichter frei verfolgen, da die Sicht klarer ist. Im Tauchmodus ist es eher n\u00fctzlich, Stellungen anzugreifen, da sich das U-Boot zu diesem Zeitpunkt in einer Tiefe von 6-30 m befand, was es f\u00fcr feindliche Schiffe schwierig machte, es zu verfolgen.<\/p>\n<h2><strong><b>Power-Batterie<\/b><\/strong><\/h2>\n<p>Die in Submarine World of Warships verf\u00fcgbaren Batterien dienen als Hauptantriebsenergie f\u00fcr das Schiff. Um den Akku weiter zu schonen, d\u00fcrfen Spieler unter Wasser oder im Sonar-Ping-Modus nicht mit voller Geschwindigkeit weiterfahren. Dadurch kann die Batterieleistung schneller entladen werden. Wenn der Akku leer ist, schaltet sich die Sonar-Ping-Funktion auf dem Schiff automatisch aus. Verwenden Sie im Wasser nur Viertelgeschwindigkeit oder beschleunigen Sie das Boot einfach im Oberfl\u00e4chenmodus.<\/p>\n<h2><strong><b>Sonar-Ping<\/b><\/strong><\/h2>\n<p>Bei der Optimierung der Sonar-Ping-Funktion m\u00fcssen die Spieler nat\u00fcrlich wissen, wie sie Batterie sparen k\u00f6nnen. W\u00e4hrend Sonar Ping ein wichtiges Men\u00fc beim Angriff auf den Feind ist. Um Sonar Ping zu verwenden, stellen Sie sicher, dass sich das Ziel in Reichweite befindet und mit einem Pfeil markiert ist. Wenn best\u00e4tigt wird, dass das Ziel erfasst ist, schie\u00dft der Torpedo automatisch auf den Feind zu. Wenn der Spieler das Ziel mit Sonar Ping erfassen kann, kann der Torpedo nat\u00fcrlich direkt auf das Ziel schie\u00dfen. Feindliche Schiffe, die mit Sonar Ping gesperrt werden, haben eine Chance von 30 Sekunden, bevor sie beschossen werden, also m\u00fcssen die Spieler in der Lage sein, dies zum richtigen Zeitpunkt zu tun. Sonar Ping hat zwei Arten von Angriffen, bestehend aus breiten und langsamen Angriffen und kurzer Reichweite mit schneller Bewegung.<\/p>\n<h2><strong><b>Grundlegende Technik<\/b><\/strong><\/h2>\n<p>Um die Submarine World of Warships zu beherrschen, m\u00fcssen die U-Boot-Daten bekannt sein. H-Taste f\u00fcr U-Boot-Detaildaten. Spieler m\u00fcssen bereits viel \u00fcber den Zustand von U-Booten wissen, wenn sie in den Kampf verwickelt sind. Um das U-Boot zu optimieren, m\u00fcssen die Spieler auch den Batterieverbrauch sowie die Strategien beim Planen feindlicher Standorte genau beachten. Das U-Boot w\u00e4re praktisch, um Kriegsschiffe mit gro\u00dfer Tonnage mit langsamen Geschwindigkeiten anzugreifen.<\/p>\n<p>Die Spieler m\u00fcssen nicht schnell auf feindliche Schiffe zielen, da sie einem Torpedoangriff definitiv entkommen. Versuchen Sie, die feindlichen Schiffe zu erschie\u00dfen, die sich direkt vor Ihnen befinden, da die Position der Submarine World of Warships-Waffe an der vorderen M\u00fcndung angebracht ist. Beim Angriff muss zuerst der Fluchtweg vorbereitet werden. Weil das U-Boot eine Bewegung hat, die dazu neigt, langsam zu sein, wodurch der Feind ohne Schwierigkeiten angreifen kann. Die Einrichtung des richtigen Fluchtwegs entscheidet also auch \u00fcber den Erfolg des Angriffs.<\/p>\n<p>Auch wenn das feindliche Schiff mit Sonar Ping gesperrt wurde, bedeutet dies nicht unbedingt, dass der gestartete Angriff das Ziel definitiv treffen wird. Die an Submarine World of Warships angebrachten Torpedowaffen haben eine Schw\u00e4che f\u00fcr Angriffe mit gekr\u00fcmmten Bahnen. Versuchen Sie daher, den Feind genau in einer geraden Linie anzuvisieren. Wenn Sie in der Zwischenzeit einen Fernangriff starten m\u00f6chten, versuchen Sie zuerst, den Torpedo zu starten, bevor Sie Sonar Ping aktivieren. Alle Torpedos greifen automatisch das Ziel an, wenn Sonar Ping es erfasst hat.<\/p>\n<p>Obwohl Sonar Ping die M\u00f6glichkeit hat, das Ziel zu sperren, wird es bei aktivem Sonar Ping leicht von Feinden gescannt. Wenn das U-Boot vom Feind gescannt wird, k\u00f6nnen feindliche Schiffe leichter mit Munition, Bomben oder Ersatzwaffen angreifen. Wenn es getroffen wird, ist die M\u00f6glichkeit des Ertrinkens gro\u00df. Wenn die Position des U-Bootes von einem gegnerischen Flugzeug gescannt wurde, wird die Position automatisch mit einem Kreis markiert.<\/p>\n<p>Die Spieler m\u00fcssen sich auch der Existenz von Zerst\u00f6rern und Kreuzern bewusst sein, die normalerweise mit Unterwasserbomben ausgestattet sind, die f\u00fcr U-Boote sehr gef\u00e4hrlich sind. Beim Steuern von Submarine World of Warships m\u00fcssen sich die Spieler w\u00e4hrend des Kampfes immer bewegen, sodass ihre Positionen schwer zu verfolgen sind.<\/p>\n<p>Verpassen Sie es nicht, immer die neuesten und vollst\u00e4ndigen Nachrichten-Updates zu Spielen zu erhalten. Angefangen von neuen Spielrezensionen, Tipps und Tricks, wie man Diamanten aufl\u00e4dt und so weiter. Folgen Sie einfach dem Konto <a href=\"https:\/\/www.instagram.com\/vcgamers.id\/\">Instagram<\/a> VCGamers und Kan\u00e4le <a href=\"https:\/\/www.youtube.com\/channel\/UC2B68_8tR2lXW8BJxqNXAMA\/videos\">Youtube<\/a> Ja.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Vor nicht allzu langer Zeit brachte der Wargaming-Entwickler Submarine auf den Markt, die neueste Klassenauswahl f\u00fcr das Spiel World of Warships. U-Boot kann f\u00fcr Farbe sorgen<\/p>","protected":false},"author":5,"featured_media":2562,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,1067],"tags":[1063,1070],"class_list":["post-2561","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-games","category-mobile-premier-league","tag-esports","tag-mpl"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tips Menguasai Submarine World of Warships<\/title>\n<meta name=\"description\" content=\"Belum lama ini developer Wargaming meluncurkan Submarine, pilihan terbaru class untuk game World of Warships. Submarine mampu memberikan warna lain\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vcgamers.com\/news\/de\/tipps-master-u-boot-world-of-warships\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tips Menguasai Submarine World of Warships\" \/>\n<meta property=\"og:description\" content=\"Belum lama ini developer Wargaming meluncurkan Submarine, pilihan terbaru class untuk game World of Warships. Submarine mampu memberikan warna lain\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vcgamers.com\/news\/de\/tipps-master-u-boot-world-of-warships\/\" \/>\n<meta property=\"og:site_name\" content=\"VCGamers News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/vcgamers.id\/\" \/>\n<meta property=\"article:author\" content=\"#\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-15T01:41:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-24T11:56:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/01\/submarine-world-of-warships.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"758\" \/>\n\t<meta property=\"og:image:height\" content=\"426\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Wulan Sari\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vcgamers_io\" \/>\n<meta name=\"twitter:site\" content=\"@vcgamers_io\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Wulan Sari\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/\"},\"author\":{\"name\":\"Wulan Sari\",\"@id\":\"https:\/\/www.vcgamers.com\/news\/#\/schema\/person\/59c1f04fe91e4c85a8454e836625ff41\"},\"headline\":\"Tips Menguasai Submarine World of Warships\",\"datePublished\":\"2021-01-15T01:41:10+00:00\",\"dateModified\":\"2021-05-24T11:56:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/\"},\"wordCount\":662,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.vcgamers.com\/news\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/01\/submarine-world-of-warships.jpg\",\"keywords\":[\"Esports\",\"MPL\"],\"articleSection\":[\"Games\",\"Mobile Premier League\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/\",\"url\":\"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/\",\"name\":\"Tips Menguasai Submarine World of Warships\",\"isPartOf\":{\"@id\":\"https:\/\/www.vcgamers.com\/news\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/01\/submarine-world-of-warships.jpg\",\"datePublished\":\"2021-01-15T01:41:10+00:00\",\"dateModified\":\"2021-05-24T11:56:05+00:00\",\"description\":\"Belum lama ini developer Wargaming meluncurkan Submarine, pilihan terbaru class untuk game World of Warships. Submarine mampu memberikan warna lain\",\"breadcrumb\":{\"@id\":\"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/#primaryimage\",\"url\":\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/01\/submarine-world-of-warships.jpg\",\"contentUrl\":\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/01\/submarine-world-of-warships.jpg\",\"width\":758,\"height\":426,\"caption\":\"Submarine World of Warships\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Beranda\",\"item\":\"https:\/\/www.vcgamers.com\/news\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Games\",\"item\":\"https:\/\/www.vcgamers.com\/news\/games\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mobile Premier League\",\"item\":\"https:\/\/www.vcgamers.com\/news\/games\/mobile-premier-league\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Tips Menguasai Submarine World of Warships\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vcgamers.com\/news\/#website\",\"url\":\"https:\/\/www.vcgamers.com\/news\/\",\"name\":\"VCGamers News - Dapatkan Berita Game Terbaru Hanya di VCGamers\",\"description\":\"Dapatkan Berita Games Terbaru Hanya di VCGamers\",\"publisher\":{\"@id\":\"https:\/\/www.vcgamers.com\/news\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vcgamers.com\/news\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.vcgamers.com\/news\/#organization\",\"name\":\"VCGamers\",\"url\":\"https:\/\/www.vcgamers.com\/news\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.vcgamers.com\/news\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2023\/05\/VCGamers-1.jpg\",\"contentUrl\":\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2023\/05\/VCGamers-1.jpg\",\"width\":500,\"height\":500,\"caption\":\"VCGamers\"},\"image\":{\"@id\":\"https:\/\/www.vcgamers.com\/news\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/vcgamers.id\/\",\"https:\/\/x.com\/vcgamers_io\",\"https:\/\/www.instagram.com\/vcgamers.id\/\",\"https:\/\/www.linkedin.com\/company\/vcgamers\/mycompany\/\",\"https:\/\/www.youtube.com\/c\/VCGamersIndonesia\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.vcgamers.com\/news\/#\/schema\/person\/59c1f04fe91e4c85a8454e836625ff41\",\"name\":\"Wulan Sari\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.vcgamers.com\/news\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2020\/12\/cod-black-ops-cold-war-cover-100x100.jpeg\",\"contentUrl\":\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2020\/12\/cod-black-ops-cold-war-cover-100x100.jpeg\",\"caption\":\"Wulan Sari\"},\"description\":\"Seorang pecinta game dan suka menuliskan pengalaman dalam bermain.\",\"sameAs\":[\"#\"],\"url\":\"https:\/\/www.vcgamers.com\/news\/de\/author\/wulan\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tipps zum Meistern der Submarine World of Warships","description":"Vor nicht allzu langer Zeit brachte der Wargaming-Entwickler Submarine auf den Markt, die neueste Klassenwahl f\u00fcr das Spiel World of Warships. U-Boot kann andere Farben liefern","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vcgamers.com\/news\/de\/tipps-master-u-boot-world-of-warships\/","og_locale":"de_DE","og_type":"article","og_title":"Tips Menguasai Submarine World of Warships","og_description":"Belum lama ini developer Wargaming meluncurkan Submarine, pilihan terbaru class untuk game World of Warships. Submarine mampu memberikan warna lain","og_url":"https:\/\/www.vcgamers.com\/news\/de\/tipps-master-u-boot-world-of-warships\/","og_site_name":"VCGamers News","article_publisher":"https:\/\/www.facebook.com\/vcgamers.id\/","article_author":"#","article_published_time":"2021-01-15T01:41:10+00:00","article_modified_time":"2021-05-24T11:56:05+00:00","og_image":[{"width":758,"height":426,"url":"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/01\/submarine-world-of-warships.jpg","type":"image\/jpeg"}],"author":"Wulan Sari","twitter_card":"summary_large_image","twitter_creator":"@vcgamers_io","twitter_site":"@vcgamers_io","twitter_misc":{"Verfasst von":"Wulan Sari","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/#article","isPartOf":{"@id":"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/"},"author":{"name":"Wulan Sari","@id":"https:\/\/www.vcgamers.com\/news\/#\/schema\/person\/59c1f04fe91e4c85a8454e836625ff41"},"headline":"Tips Menguasai Submarine World of Warships","datePublished":"2021-01-15T01:41:10+00:00","dateModified":"2021-05-24T11:56:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/"},"wordCount":662,"commentCount":0,"publisher":{"@id":"https:\/\/www.vcgamers.com\/news\/#organization"},"image":{"@id":"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/01\/submarine-world-of-warships.jpg","keywords":["Esports","MPL"],"articleSection":["Games","Mobile Premier League"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/","url":"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/","name":"Tipps zum Meistern der Submarine World of Warships","isPartOf":{"@id":"https:\/\/www.vcgamers.com\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/#primaryimage"},"image":{"@id":"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/01\/submarine-world-of-warships.jpg","datePublished":"2021-01-15T01:41:10+00:00","dateModified":"2021-05-24T11:56:05+00:00","description":"Vor nicht allzu langer Zeit brachte der Wargaming-Entwickler Submarine auf den Markt, die neueste Klassenwahl f\u00fcr das Spiel World of Warships. U-Boot kann andere Farben liefern","breadcrumb":{"@id":"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/#primaryimage","url":"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/01\/submarine-world-of-warships.jpg","contentUrl":"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/01\/submarine-world-of-warships.jpg","width":758,"height":426,"caption":"Submarine World of Warships"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vcgamers.com\/news\/tips-menguasai-submarine-world-of-warships\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Beranda","item":"https:\/\/www.vcgamers.com\/news\/"},{"@type":"ListItem","position":2,"name":"Games","item":"https:\/\/www.vcgamers.com\/news\/games\/"},{"@type":"ListItem","position":3,"name":"Mobile Premier League","item":"https:\/\/www.vcgamers.com\/news\/games\/mobile-premier-league\/"},{"@type":"ListItem","position":4,"name":"Tips Menguasai Submarine World of Warships"}]},{"@type":"WebSite","@id":"https:\/\/www.vcgamers.com\/news\/#website","url":"https:\/\/www.vcgamers.com\/news\/","name":"VCGamers News - Holen Sie sich die neuesten Spiele-News nur bei VCGamers","description":"Holen Sie sich die neuesten Spielnachrichten nur bei VCGamers","publisher":{"@id":"https:\/\/www.vcgamers.com\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vcgamers.com\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.vcgamers.com\/news\/#organization","name":"VCGamers","url":"https:\/\/www.vcgamers.com\/news\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vcgamers.com\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2023\/05\/VCGamers-1.jpg","contentUrl":"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2023\/05\/VCGamers-1.jpg","width":500,"height":500,"caption":"VCGamers"},"image":{"@id":"https:\/\/www.vcgamers.com\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/vcgamers.id\/","https:\/\/x.com\/vcgamers_io","https:\/\/www.instagram.com\/vcgamers.id\/","https:\/\/www.linkedin.com\/company\/vcgamers\/mycompany\/","https:\/\/www.youtube.com\/c\/VCGamersIndonesia"]},{"@type":"Person","@id":"https:\/\/www.vcgamers.com\/news\/#\/schema\/person\/59c1f04fe91e4c85a8454e836625ff41","name":"Wulansari","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vcgamers.com\/news\/#\/schema\/person\/image\/","url":"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2020\/12\/cod-black-ops-cold-war-cover-100x100.jpeg","contentUrl":"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2020\/12\/cod-black-ops-cold-war-cover-100x100.jpeg","caption":"Wulan Sari"},"description":"Ein Spieleliebhaber und schreibt gerne \u00fcber Spielerfahrungen.","sameAs":["#"],"url":"https:\/\/www.vcgamers.com\/news\/de\/author\/wulan\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vcgamers.com\/news\/de\/wp-json\/wp\/v2\/posts\/2561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vcgamers.com\/news\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vcgamers.com\/news\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vcgamers.com\/news\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vcgamers.com\/news\/de\/wp-json\/wp\/v2\/comments?post=2561"}],"version-history":[{"count":0,"href":"https:\/\/www.vcgamers.com\/news\/de\/wp-json\/wp\/v2\/posts\/2561\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vcgamers.com\/news\/de\/wp-json\/wp\/v2\/media\/2562"}],"wp:attachment":[{"href":"https:\/\/www.vcgamers.com\/news\/de\/wp-json\/wp\/v2\/media?parent=2561"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vcgamers.com\/news\/de\/wp-json\/wp\/v2\/categories?post=2561"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vcgamers.com\/news\/de\/wp-json\/wp\/v2\/tags?post=2561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}