{"id":25225,"date":"2021-08-27T13:10:00","date_gmt":"2021-08-27T06:10:00","guid":{"rendered":"https:\/\/www.vcgamers.com\/news\/?p=25225"},"modified":"2022-10-03T15:54:08","modified_gmt":"2022-10-03T08:54:08","slug":"kadita-hero-herkunft-indonesien-muss-combo","status":"publish","type":"post","link":"https:\/\/www.vcgamers.com\/news\/de\/kadita-hero-asal-indonesia-harus-combo\/","title":{"rendered":"Kadita, ein Held aus Indonesien, der eine Combo haben muss!"},"content":{"rendered":"<p>Hola Viciger! <em>Helden <\/em>K\u00f6nigin der S\u00fcdsee <em><em><a href=\"https:\/\/m.mobilelegends.com\/en\" target=\"_blank\" rel=\"noreferrer noopener\">Mobile Legenden: Bang Bang<\/a><\/em><\/em>, <em>Kadita<\/em>Sie ist eine Prinzessin eines kleinen K\u00f6nigreichs. <em>Helden <\/em>Wer geschickt darin ist, Meerwasser und das Wetter zu kontrollieren, wird gef\u00fcrchtet, weil es werden kann <em>Helden <\/em>was gef\u00e4hrlich ist. Mit <em>Rolle Magier<\/em> und Spezialisierung als <em>Held platzte<\/em> oder <em>Aufladung<\/em> mach es <em>Magier <\/em>was t\u00f6dlich ist.<\/p>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">\u00dcbersicht \u00dcber <em>Held Kadita<\/em><\/h2>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"632\" class=\"wp-image-4289\" src=\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/03\/kadita-1024x632.jpg\" alt=\"\" srcset=\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/03\/kadita-1024x632.jpg 1024w, https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/03\/kadita-300x185.jpg 300w, https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/03\/kadita-768x474.jpg 768w, https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/03\/kadita-1144x706.jpg 1144w, https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/03\/kadita-720x444.jpg 720w, https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/03\/kadita-250x154.jpg 250w, https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/03\/kadita.jpg 1241w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<p><em>F\u00e4higkeiten <\/em>die im Besitz sind <em>Helden <\/em>das ist sehr einzigartig, denn passiv hat er <em>Segen <\/em>aus <em>Macht des Ozeans<\/em> was bedeutet <em>Helden<\/em> Dadurch wird der 65% wiederhergestellt <em>MOBILTELEFON-<\/em>die bei einem Treffer verloren geht <em>Schaden<\/em> alle 30 Sekunden. Sein Passiv ist n\u00fctzlich genug, um Gegner herauszulocken <em>F\u00e4higkeiten<\/em>-sein.<\/p>\r\n\r\n\r\n\r\n<p><em>F\u00e4higkeiten<\/em> Erste <em>Kadita <\/em>\u00a0Werde eine Meerjungfrau und beschw\u00f6re die Meereswellen, um zu liefern <em>Schaden<\/em> in eine bestimmte Richtung, wodurch ein Effekt entsteht <em>langsam<\/em> und Wirkung erzielen <em>immun<\/em> gegen alle <em>F\u00e4higkeiten<\/em> <em>Massenkontrolle<\/em>.<\/p>\r\n\r\n\r\n\r\n<p><em>F\u00e4higkeiten <\/em>es ist wiederverwendbar, wenn es wiederverwendet wird <em>Helden<\/em> es wird aus der Welle herauskommen und die Welle wird sich von selbst bewegen.<\/p>\r\n\r\n\r\n\r\n<p><em>F\u00e4higkeiten <\/em>Zweitens wird er Meereswellen wieder in Fl\u00e4chenform beschw\u00f6ren, nach ein paar Sekunden kommen die Wellen aus dem Boden und verursachen Effekte <em>in der Luft<\/em> zum Gegner.<\/p>\r\n\r\n\r\n\r\n<p><em>F\u00e4higkeiten <\/em>drei <em>Helden<\/em> Dies wird einen Tsunami ausl\u00f6sen, um den Gegner in verschiedene Richtungen zu zerst\u00f6ren. Ursache Wirkung <em>langsam<\/em> und je mehr Wellen den Gegner treffen, desto mehr <em>Schaden <\/em>die er erhielt.<\/p>\r\n\r\n\r\n\r\n<p>Danach <em>Kadita <\/em>wird zur\u00fcckkommen und die Wellen zu sich ziehen. Das ist eine kurze Erkl\u00e4rung dazu <em>F\u00e4higkeiten<\/em> <em>Kadita <\/em>f\u00fcr diejenigen unter Ihnen, die nicht wissen und verstehen k\u00f6nnen, wie man spielt <em>Helden <\/em>Das. Jetzt f\u00fcr <em>Tipps <\/em>Und <em>Trick<\/em> wenn du spielen willst <em>Kadita <\/em>Also.<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-full\"><img decoding=\"async\" class=\"wp-image-20909\" src=\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/08\/Kadita-Item-Fleeting-Time-ML.jpg\" alt=\"Kadita-Item-Fleeting-Time-ML\" \/><\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\"><em>Tipps <\/em>Und <em>Tricks <\/em>Spielen <em>Kadita<\/em><\/h2>\r\n\r\n\r\n\r\n<p><em>Kadita <\/em>sehr gut zum spielen geeignet <em>Mittellaner<\/em> weil es kann <em>klare G\u00fcnstlinge<\/em> der schnell genug ist und sich drehen kann, um zu helfen <em>Fahrspuren <\/em>andere. Du kannst es auch reinstellen <em>Gold<\/em> <em>Fahrspuren<\/em> aber es w\u00e4re ein Nachteil, wenn sein Gegner <em>Sch\u00fctzen<\/em> weil Sie aus der Ferne zur\u00fcckzahlen k\u00f6nnen.<\/p>\r\n\r\n\r\n\r\n<p>F\u00fcr <em>vollen Schaden bauen<\/em> ihr k\u00f6nnt machen <em>D\u00e4monenschuhe, Uhr des Schicksals, Leuchtkn\u00fcppel, Zauberstab des Genies, G\u00f6ttliche Gleve, <\/em>Und <em>Winterkn\u00fcppel. baut <\/em>Dies ist besser zu verwenden, wenn Sie sich in einem Zustand des Sieges oder eines Unentschiedens befinden. Schwierig wird es, wenn Sie sich in einer Verlustposition befinden <em>Artikel<\/em> so was.<\/p>\r\n\r\n\r\n\r\n<p><em>Alternative Builds <\/em>was du tun kannst ist <em>Arkane Stiefel, Verzauberter Talisman, Konzentrierte Energie, Halsband der Durance, Heiliger Kristall, G\u00f6ttliche Gleve. <\/em>Auf diese Weise ist es ziemlich stabil in der Lieferung <em>Schaden <\/em>Und <em>Kaditas Verteidigung.<\/em><\/p>\r\n\r\n\r\n\r\n<p><em>baut <\/em>es liefert einfach nicht <em>Schaden <\/em>so gro\u00df <em>bauen <\/em>zuerst, aber es w\u00e4re besser zu machen <em>Artikel <\/em>was billiger und effektiver ist, wenn Sie sich in einer schwierigen Situation befinden <em>Landwirtschaft<\/em>.<\/p>\r\n\r\n\r\n\r\n<p><em>Kadita <\/em>Dies ist einer <em>Helden <\/em>popularisiert von Godiva als <em>Profispieler von Mobile Legends. <\/em>Es gibt verschiedene Taktiken, die Sie in verschiedenen Situationen anwenden k\u00f6nnen, z <em>Sack <\/em>zum Gegner sogar tat <em>sofortige Kills<\/em>.<\/p>\r\n\r\n\r\n\r\n<p>Ihr k\u00f6nnt das tun <em>Sack <\/em>zum Gegner durch das Tun <em>Spam-F\u00e4higkeiten<\/em> Eins. Scheuen Sie sich nicht, vorw\u00e4rts zu gehen, wenn Sie ein passives From haben <em>Kadita<\/em>. Versuche es <em>handeln<\/em> <em>MOBILTELEFON<\/em> mit Feinden.<\/p>\r\n\r\n\r\n\r\n<p>Verwenden <em>F\u00e4higkeiten<\/em> Zweitens, indem Sie die Bewegung des Feindes vorhersagen, da das Erscheinen der Wellen einige Sekunden sp\u00e4ter herauskommt <em>F\u00e4higkeiten<\/em> gebraucht.<\/p>\r\n\r\n\r\n\r\n<p>F\u00fcr <em>Instant-Kill-Combo<\/em> Sie alle sorgen daf\u00fcr <em>F\u00e4higkeiten<\/em> bereit und <em>Zauber<\/em> was normalerweise getragen wird, ist versteinert, damit sich der Feind nicht bewegen kann. Verstecken Sie sich zuerst in den B\u00fcschen, und verwenden Sie es dann, wenn der Gegner in die B\u00fcsche eindringt <em>F\u00e4higkeiten<\/em> zwei, damit der Feind wirksam wird <em>in der Luft<\/em>.<\/p>\r\n\r\n\r\n\r\n<pre class=\"wp-block-verse\"><strong><em>Lesen Sie auch: <a class=\"rank-math-link\" href=\"https:\/\/www.vcgamers.com\/news\/de\/25223-avatar-mlbb-ngebosenin-kalau-ga-berbingkai\/\" data-type=\"post\" data-id=\"25223\">Dein MLBB-Avatar ist ohne Frames langweilig!<\/a><\/em><\/strong><\/pre>\r\n\r\n\r\n\r\n<p>Nach der Wirkung <em>in der Luft<\/em> Sie k\u00f6nnen es sofort verwenden <em>F\u00e4higkeiten<\/em> ein- oder zweimal <em>Kadita <\/em>noch vorhanden und in Gebrauch <em>ultimative<\/em> gleich rein <em>Helden <\/em>gegen.<\/p>\r\n\r\n\r\n\r\n<p>Wenn der Gegner ist <em>Helden <\/em>welche Agile Sie verwenden k\u00f6nnen <em>versteinern <\/em>Zuerst, dann <em>F\u00e4higkeiten<\/em> zwei, <em>F\u00e4higkeiten <\/em>ein- und zweimal <em>ultimative<\/em> sofort wird der Feind eliminiert, ohne Zeit zum Ausgeben zu haben <em>F\u00e4higkeiten<\/em> oder weglaufen.<\/p>\r\n\r\n\r\n\r\n<p>Versuchen Sie, aus verschiedenen Videos zu sehen <em>professioneller Spieler <\/em>Spielen Sie wie Godiva oder andere, damit Sie es besser verstehen und reibungsloser verwenden k\u00f6nnen <em>Kadita-Held <\/em>Das.<\/p>\r\n\r\n\r\n\r\n<p>Sie m\u00fcssen sich daran erinnern, dass Sie durch kontinuierliches \u00dcben kompetent und klug im Bestimmen werden <em>Zeiten<\/em> verwenden <em>Kaditas F\u00e4higkeiten<\/em>. Viel Gl\u00fcck!<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.vcgamers.com\/news\/de\/18017-promo-khusus-seller-bebas-biaya-penjualan\/\"><img decoding=\"async\" width=\"1024\" height=\"284\" class=\"wp-image-24982\" src=\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/08\/vcgamers-bebas-biaya-transaksi-penjualan-02-26-1024x284.png\" alt=\"\" srcset=\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/08\/vcgamers-bebas-biaya-transaksi-penjualan-02-26-1024x284.png 1024w, https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/08\/vcgamers-bebas-biaya-transaksi-penjualan-02-26-300x83.png 300w, https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/08\/vcgamers-bebas-biaya-transaksi-penjualan-02-26-768x213.png 768w, https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/08\/vcgamers-bebas-biaya-transaksi-penjualan-02-26-1144x317.png 1144w, https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/08\/vcgamers-bebas-biaya-transaksi-penjualan-02-26-720x200.png 720w, https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/08\/vcgamers-bebas-biaya-transaksi-penjualan-02-26-250x69.png 250w, https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/08\/vcgamers-bebas-biaya-transaksi-penjualan-02-26.png 1334w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>","protected":false},"excerpt":{"rendered":"<p>Hola Vicigers! Die Heldin der K\u00f6nigin der s\u00fcdlichen Meere von Mobile Legends: Bang Bang, Kadita, ist eine Prinzessin aus einem kleinen K\u00f6nigreich. Held das<\/p>","protected":false},"author":24,"featured_media":20909,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,1058],"tags":[1069],"class_list":["post-25225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-games","category-mobile-legends","tag-mobile-legends"],"pp_statuses_selecting_workflow":false,"pp_workflow_action":"current","pp_status_selection":"publish","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kadita, Hero Asal Indonesia yang Harus Combo Biar Berguna!<\/title>\n<meta name=\"description\" content=\"Hola Vicigers! Hero ratu laut selatan Mobile Legends: Bang Bang, Kadita, adalah seorang putri dari kerajaan kecil. Hero yang mahir mengendalikan air\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vcgamers.com\/news\/de\/kadita-hero-herkunft-indonesien-muss-combo\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kadita, Hero Asal Indonesia yang Harus Combo Biar Berguna!\" \/>\n<meta property=\"og:description\" content=\"Hola Vicigers! Hero ratu laut selatan Mobile Legends: Bang Bang, Kadita, adalah seorang putri dari kerajaan kecil. Hero yang mahir mengendalikan air\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vcgamers.com\/news\/de\/kadita-hero-herkunft-indonesien-muss-combo\/\" \/>\n<meta property=\"og:site_name\" content=\"VCGamers News\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/vcgamers.id\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-27T06:10:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-03T08:54:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/08\/Kadita-Item-Fleeting-Time-ML-e1630646355395.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"255\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Abraham Alkhaf\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@vcgamers_io\" \/>\n<meta name=\"twitter:site\" content=\"@vcgamers_io\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Abraham Alkhaf\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/\"},\"author\":{\"name\":\"Abraham Alkhaf\",\"@id\":\"https:\/\/www.vcgamers.com\/news\/#\/schema\/person\/f3c6b215f8b6df8fb9844993bdd61f75\"},\"headline\":\"Kadita, Hero Asal Indonesia yang Harus Combo Biar Berguna!\",\"datePublished\":\"2021-08-27T06:10:00+00:00\",\"dateModified\":\"2022-10-03T08:54:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/\"},\"wordCount\":610,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.vcgamers.com\/news\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/08\/Kadita-Item-Fleeting-Time-ML-e1630646355395.jpg\",\"keywords\":[\"Mobile Legends\"],\"articleSection\":[\"Games\",\"Mobile Legends\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/\",\"url\":\"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/\",\"name\":\"Kadita, Hero Asal Indonesia yang Harus Combo Biar Berguna!\",\"isPartOf\":{\"@id\":\"https:\/\/www.vcgamers.com\/news\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/08\/Kadita-Item-Fleeting-Time-ML-e1630646355395.jpg\",\"datePublished\":\"2021-08-27T06:10:00+00:00\",\"dateModified\":\"2022-10-03T08:54:08+00:00\",\"description\":\"Hola Vicigers! Hero ratu laut selatan Mobile Legends: Bang Bang, Kadita, adalah seorang putri dari kerajaan kecil. Hero yang mahir mengendalikan air\",\"breadcrumb\":{\"@id\":\"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/#primaryimage\",\"url\":\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/08\/Kadita-Item-Fleeting-Time-ML-e1630646355395.jpg\",\"contentUrl\":\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/08\/Kadita-Item-Fleeting-Time-ML-e1630646355395.jpg\",\"width\":700,\"height\":255,\"caption\":\"Hero Nyi Roro Kidul\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Beranda\",\"item\":\"https:\/\/www.vcgamers.com\/news\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Games\",\"item\":\"https:\/\/www.vcgamers.com\/news\/games\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mobile Legends\",\"item\":\"https:\/\/www.vcgamers.com\/news\/games\/mobile-legends\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Kadita, Hero Asal Indonesia yang Harus Combo Biar Berguna!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.vcgamers.com\/news\/#website\",\"url\":\"https:\/\/www.vcgamers.com\/news\/\",\"name\":\"VCGamers News - Dapatkan Berita Game Terbaru Hanya di VCGamers\",\"description\":\"Dapatkan Berita Games Terbaru Hanya di VCGamers\",\"publisher\":{\"@id\":\"https:\/\/www.vcgamers.com\/news\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.vcgamers.com\/news\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.vcgamers.com\/news\/#organization\",\"name\":\"VCGamers\",\"url\":\"https:\/\/www.vcgamers.com\/news\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.vcgamers.com\/news\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2023\/05\/VCGamers-1.jpg\",\"contentUrl\":\"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2023\/05\/VCGamers-1.jpg\",\"width\":500,\"height\":500,\"caption\":\"VCGamers\"},\"image\":{\"@id\":\"https:\/\/www.vcgamers.com\/news\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/vcgamers.id\/\",\"https:\/\/x.com\/vcgamers_io\",\"https:\/\/www.instagram.com\/vcgamers.id\/\",\"https:\/\/www.linkedin.com\/company\/vcgamers\/mycompany\/\",\"https:\/\/www.youtube.com\/c\/VCGamersIndonesia\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.vcgamers.com\/news\/#\/schema\/person\/f3c6b215f8b6df8fb9844993bdd61f75\",\"name\":\"Abraham Alkhaf\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.vcgamers.com\/news\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/storage.googleapis.com\/cdn.vcgamers.com\/news\/wp-content\/uploads\/2023\/12\/Vicimon-v4-150x150.png.webp\",\"contentUrl\":\"https:\/\/storage.googleapis.com\/cdn.vcgamers.com\/news\/wp-content\/uploads\/2023\/12\/Vicimon-v4-150x150.png.webp\",\"caption\":\"Abraham Alkhaf\"},\"url\":\"https:\/\/www.vcgamers.com\/news\/de\/author\/abrahamalkhaf\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kadita, ein Held aus Indonesien, der eine Combo haben muss!","description":"Hola Viciger! Die Heldin der K\u00f6nigin der s\u00fcdlichen Meere von Mobile Legends: Bang Bang, Kadita, ist eine Prinzessin aus einem kleinen K\u00f6nigreich. Ein Held, der geschickt darin ist, Wasser zu kontrollieren","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vcgamers.com\/news\/de\/kadita-hero-herkunft-indonesien-muss-combo\/","og_locale":"de_DE","og_type":"article","og_title":"Kadita, Hero Asal Indonesia yang Harus Combo Biar Berguna!","og_description":"Hola Vicigers! Hero ratu laut selatan Mobile Legends: Bang Bang, Kadita, adalah seorang putri dari kerajaan kecil. Hero yang mahir mengendalikan air","og_url":"https:\/\/www.vcgamers.com\/news\/de\/kadita-hero-herkunft-indonesien-muss-combo\/","og_site_name":"VCGamers News","article_publisher":"https:\/\/www.facebook.com\/vcgamers.id\/","article_published_time":"2021-08-27T06:10:00+00:00","article_modified_time":"2022-10-03T08:54:08+00:00","og_image":[{"width":700,"height":255,"url":"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/08\/Kadita-Item-Fleeting-Time-ML-e1630646355395.jpg","type":"image\/jpeg"}],"author":"Abraham Alkhaf","twitter_card":"summary_large_image","twitter_creator":"@vcgamers_io","twitter_site":"@vcgamers_io","twitter_misc":{"Verfasst von":"Abraham Alkhaf","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/#article","isPartOf":{"@id":"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/"},"author":{"name":"Abraham Alkhaf","@id":"https:\/\/www.vcgamers.com\/news\/#\/schema\/person\/f3c6b215f8b6df8fb9844993bdd61f75"},"headline":"Kadita, Hero Asal Indonesia yang Harus Combo Biar Berguna!","datePublished":"2021-08-27T06:10:00+00:00","dateModified":"2022-10-03T08:54:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/"},"wordCount":610,"commentCount":0,"publisher":{"@id":"https:\/\/www.vcgamers.com\/news\/#organization"},"image":{"@id":"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/08\/Kadita-Item-Fleeting-Time-ML-e1630646355395.jpg","keywords":["Mobile Legends"],"articleSection":["Games","Mobile Legends"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/","url":"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/","name":"Kadita, ein Held aus Indonesien, der eine Combo haben muss!","isPartOf":{"@id":"https:\/\/www.vcgamers.com\/news\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/#primaryimage"},"image":{"@id":"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/08\/Kadita-Item-Fleeting-Time-ML-e1630646355395.jpg","datePublished":"2021-08-27T06:10:00+00:00","dateModified":"2022-10-03T08:54:08+00:00","description":"Hola Viciger! Die Heldin der K\u00f6nigin der s\u00fcdlichen Meere von Mobile Legends: Bang Bang, Kadita, ist eine Prinzessin aus einem kleinen K\u00f6nigreich. Ein Held, der geschickt darin ist, Wasser zu kontrollieren","breadcrumb":{"@id":"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/#primaryimage","url":"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/08\/Kadita-Item-Fleeting-Time-ML-e1630646355395.jpg","contentUrl":"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2021\/08\/Kadita-Item-Fleeting-Time-ML-e1630646355395.jpg","width":700,"height":255,"caption":"Hero Nyi Roro Kidul"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vcgamers.com\/news\/kadita-hero-asal-indonesia-harus-combo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Beranda","item":"https:\/\/www.vcgamers.com\/news\/"},{"@type":"ListItem","position":2,"name":"Games","item":"https:\/\/www.vcgamers.com\/news\/games\/"},{"@type":"ListItem","position":3,"name":"Mobile Legends","item":"https:\/\/www.vcgamers.com\/news\/games\/mobile-legends\/"},{"@type":"ListItem","position":4,"name":"Kadita, Hero Asal Indonesia yang Harus Combo Biar Berguna!"}]},{"@type":"WebSite","@id":"https:\/\/www.vcgamers.com\/news\/#website","url":"https:\/\/www.vcgamers.com\/news\/","name":"VCGamers News - Holen Sie sich die neuesten Spiele-News nur bei VCGamers","description":"Holen Sie sich die neuesten Spielnachrichten nur bei VCGamers","publisher":{"@id":"https:\/\/www.vcgamers.com\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vcgamers.com\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.vcgamers.com\/news\/#organization","name":"VCGamers","url":"https:\/\/www.vcgamers.com\/news\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vcgamers.com\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2023\/05\/VCGamers-1.jpg","contentUrl":"https:\/\/www.vcgamers.com\/news\/wp-content\/uploads\/2023\/05\/VCGamers-1.jpg","width":500,"height":500,"caption":"VCGamers"},"image":{"@id":"https:\/\/www.vcgamers.com\/news\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/vcgamers.id\/","https:\/\/x.com\/vcgamers_io","https:\/\/www.instagram.com\/vcgamers.id\/","https:\/\/www.linkedin.com\/company\/vcgamers\/mycompany\/","https:\/\/www.youtube.com\/c\/VCGamersIndonesia"]},{"@type":"Person","@id":"https:\/\/www.vcgamers.com\/news\/#\/schema\/person\/f3c6b215f8b6df8fb9844993bdd61f75","name":"Abraham Alkaff","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.vcgamers.com\/news\/#\/schema\/person\/image\/","url":"https:\/\/storage.googleapis.com\/cdn.vcgamers.com\/news\/wp-content\/uploads\/2023\/12\/Vicimon-v4-150x150.png.webp","contentUrl":"https:\/\/storage.googleapis.com\/cdn.vcgamers.com\/news\/wp-content\/uploads\/2023\/12\/Vicimon-v4-150x150.png.webp","caption":"Abraham Alkhaf"},"url":"https:\/\/www.vcgamers.com\/news\/de\/author\/abrahamalkhaf\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vcgamers.com\/news\/de\/wp-json\/wp\/v2\/posts\/25225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vcgamers.com\/news\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vcgamers.com\/news\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vcgamers.com\/news\/de\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vcgamers.com\/news\/de\/wp-json\/wp\/v2\/comments?post=25225"}],"version-history":[{"count":0,"href":"https:\/\/www.vcgamers.com\/news\/de\/wp-json\/wp\/v2\/posts\/25225\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vcgamers.com\/news\/de\/wp-json\/wp\/v2\/media\/20909"}],"wp:attachment":[{"href":"https:\/\/www.vcgamers.com\/news\/de\/wp-json\/wp\/v2\/media?parent=25225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vcgamers.com\/news\/de\/wp-json\/wp\/v2\/categories?post=25225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vcgamers.com\/news\/de\/wp-json\/wp\/v2\/tags?post=25225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}